{"id":4,"date":"2020-01-05T16:59:04","date_gmt":"2020-01-05T15:59:04","guid":{"rendered":"http:\/\/cliniqueveterinairemistral.com\/?p=4"},"modified":"2020-12-05T16:43:04","modified_gmt":"2020-12-05T15:43:04","slug":"accueil","status":"publish","type":"post","link":"https:\/\/cliniqueveterinairemistral.com\/index.php\/2020\/01\/05\/accueil\/","title":{"rendered":"Accueil"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">C&rsquo;est avec un plaisir certain que nous vous accueillons sur notre vitrine internet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Notre \u00e9quipe de v\u00e9t\u00e9rinaires et d&rsquo;ASV est au service de la sant\u00e9 de vos animaux afin de vous proposer la meilleure qualit\u00e9 de soins possible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aux consultations de m\u00e9decine g\u00e9n\u00e9rale et traditionnelle, nous avons ajout\u00e9 depuis  quelques ann\u00e9es  des consultations sp\u00e9cialis\u00e9es de <strong>phytoth\u00e9rapie, ost\u00e9opathie et acupuncture.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lors de vos visites, n&rsquo;h\u00e9sitez pas \u00e0 demander conseil, prendre rendez-vous ou vous renseigner sur les produits destin\u00e9s au bien-\u00eatre de vos compagnons.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"alignnormal\"><div id=\"metaslider-id-191\" style=\"width: 100%;\" class=\"ml-slider-3-110-0 metaslider metaslider-flex metaslider-191 ml-slider has-dots-nav has-carousel-mode ms-theme-default\" role=\"region\" aria-label=\"Clinique\" data-height=\"400\" data-width=\"600\">\n    <div id=\"metaslider_container_191\">\n        <div id=\"metaslider_191\" class=\"flexslider\">\n            <ul class='slides'>\n                <li style=\"display: none; width: 100%;\" class=\"slide-476 ms-image \" aria-roledescription=\"slide\" data-date=\"2022-06-22 10:23:50\" data-filename=\"IMG_4699-scaled-600x400.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cliniqueveterinairemistral.com\/wp-content\/uploads\/2022\/06\/IMG_4699-scaled-600x400.jpg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-191 slide-476 msDefaultImage\" title=\"IMG_4699\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-477 ms-image \" aria-roledescription=\"slide\" data-date=\"2022-06-22 10:24:04\" data-filename=\"IMG_E4700-scaled-600x400.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cliniqueveterinairemistral.com\/wp-content\/uploads\/2022\/06\/IMG_E4700-scaled-600x400.jpg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-191 slide-477 msDefaultImage\" title=\"IMG_E4700\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-478 ms-image \" aria-roledescription=\"slide\" data-date=\"2022-06-22 10:24:25\" data-filename=\"IMG_4690-scaled-600x400.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cliniqueveterinairemistral.com\/wp-content\/uploads\/2022\/06\/IMG_4690-scaled-600x400.jpg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-191 slide-478 msDefaultImage\" title=\"IMG_4690\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-479 ms-image \" aria-roledescription=\"slide\" data-date=\"2022-06-22 10:24:48\" data-filename=\"IMG_4685-scaled-600x400.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cliniqueveterinairemistral.com\/wp-content\/uploads\/2022\/06\/IMG_4685-scaled-600x400.jpg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-191 slide-479 msDefaultImage\" title=\"IMG_4685\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-480 ms-image \" aria-roledescription=\"slide\" data-date=\"2022-06-22 10:25:13\" data-filename=\"IMG_E4728-scaled-600x400.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cliniqueveterinairemistral.com\/wp-content\/uploads\/2022\/06\/IMG_E4728-scaled-600x400.jpg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-191 slide-480 msDefaultImage\" title=\"IMG_E4728\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-481 ms-image \" aria-roledescription=\"slide\" data-date=\"2022-06-22 10:25:32\" data-filename=\"IMG_E4688-scaled-600x400.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cliniqueveterinairemistral.com\/wp-content\/uploads\/2022\/06\/IMG_E4688-scaled-600x400.jpg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-191 slide-481 msDefaultImage\" title=\"IMG_E4688\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-482 ms-image \" aria-roledescription=\"slide\" data-date=\"2022-06-22 10:25:48\" data-filename=\"IMG_4716-scaled-600x400.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cliniqueveterinairemistral.com\/wp-content\/uploads\/2022\/06\/IMG_4716-scaled-600x400.jpg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-191 slide-482 msDefaultImage\" title=\"IMG_4716\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-483 ms-image \" aria-roledescription=\"slide\" data-date=\"2022-06-22 10:26:07\" data-filename=\"IMG_4713-scaled-600x400.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cliniqueveterinairemistral.com\/wp-content\/uploads\/2022\/06\/IMG_4713-scaled-600x400.jpg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-191 slide-483 msDefaultImage\" title=\"IMG_4713\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-484 ms-image \" aria-roledescription=\"slide\" data-date=\"2022-06-22 10:26:22\" data-filename=\"IMG_4726-scaled-600x400.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cliniqueveterinairemistral.com\/wp-content\/uploads\/2022\/06\/IMG_4726-scaled-600x400.jpg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-191 slide-484 msDefaultImage\" title=\"IMG_4726\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-486 ms-image \" aria-roledescription=\"slide\" data-date=\"2022-06-22 10:27:14\" data-filename=\"IMG_4725-scaled-600x400.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cliniqueveterinairemistral.com\/wp-content\/uploads\/2022\/06\/IMG_4725-scaled-600x400.jpg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-191 slide-486 msDefaultImage\" title=\"IMG_4725\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-487 ms-image \" aria-roledescription=\"slide\" data-date=\"2022-06-22 10:27:28\" data-filename=\"IMG_4721-scaled-600x400.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cliniqueveterinairemistral.com\/wp-content\/uploads\/2022\/06\/IMG_4721-scaled-600x400.jpg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-191 slide-487 msDefaultImage\" title=\"IMG_4721\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-488 ms-image \" aria-roledescription=\"slide\" data-date=\"2022-06-22 10:27:39\" data-filename=\"IMG_4712-scaled-600x400.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cliniqueveterinairemistral.com\/wp-content\/uploads\/2022\/06\/IMG_4712-scaled-600x400.jpg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-191 slide-488 msDefaultImage\" title=\"IMG_4712\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-489 ms-image \" aria-roledescription=\"slide\" data-date=\"2022-06-22 10:27:56\" data-filename=\"IMG_4684-scaled-600x400.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cliniqueveterinairemistral.com\/wp-content\/uploads\/2022\/06\/IMG_4684-scaled-600x400.jpg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-191 slide-489 msDefaultImage\" title=\"IMG_4684\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-490 ms-image \" aria-roledescription=\"slide\" data-date=\"2022-06-22 10:28:06\" data-filename=\"IMG_4683-scaled-600x400.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cliniqueveterinairemistral.com\/wp-content\/uploads\/2022\/06\/IMG_4683-scaled-600x400.jpg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-191 slide-490 msDefaultImage\" title=\"IMG_4683\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-491 ms-image \" aria-roledescription=\"slide\" data-date=\"2022-06-22 10:28:19\" data-filename=\"IMG_4682-scaled-600x400.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cliniqueveterinairemistral.com\/wp-content\/uploads\/2022\/06\/IMG_4682-scaled-600x400.jpg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-191 slide-491 msDefaultImage\" title=\"IMG_4682\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-492 ms-image \" aria-roledescription=\"slide\" data-date=\"2022-06-22 10:28:51\" data-filename=\"IMG_4707-scaled-600x400.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cliniqueveterinairemistral.com\/wp-content\/uploads\/2022\/06\/IMG_4707-scaled-600x400.jpg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-191 slide-492 msDefaultImage\" title=\"IMG_4707\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-493 ms-image \" aria-roledescription=\"slide\" data-date=\"2022-06-22 10:29:01\" data-filename=\"IMG_4702-scaled-600x400.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cliniqueveterinairemistral.com\/wp-content\/uploads\/2022\/06\/IMG_4702-scaled-600x400.jpg\" height=\"400\" width=\"600\" alt=\"\" class=\"slider-191 slide-493 msDefaultImage\" title=\"IMG_4702\" \/><\/li>\n            <\/ul>\n        <\/div>\n        \n    <\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>C&rsquo;est avec un plaisir certain que nous vous accueillons sur notre vitrine internet. Notre \u00e9quipe de v\u00e9t\u00e9rinaires et d&rsquo;ASV est au service de la sant\u00e9 de vos animaux afin de vous proposer la meilleure qualit\u00e9 de soins possible. Aux consultations de m\u00e9decine g\u00e9n\u00e9rale et traditionnelle, nous avons ajout\u00e9 depuis quelques [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4","post","type-post","status-publish","format-standard","hentry","category-clinique"],"_links":{"self":[{"href":"https:\/\/cliniqueveterinairemistral.com\/index.php\/wp-json\/wp\/v2\/posts\/4","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cliniqueveterinairemistral.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cliniqueveterinairemistral.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cliniqueveterinairemistral.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cliniqueveterinairemistral.com\/index.php\/wp-json\/wp\/v2\/comments?post=4"}],"version-history":[{"count":7,"href":"https:\/\/cliniqueveterinairemistral.com\/index.php\/wp-json\/wp\/v2\/posts\/4\/revisions"}],"predecessor-version":[{"id":441,"href":"https:\/\/cliniqueveterinairemistral.com\/index.php\/wp-json\/wp\/v2\/posts\/4\/revisions\/441"}],"wp:attachment":[{"href":"https:\/\/cliniqueveterinairemistral.com\/index.php\/wp-json\/wp\/v2\/media?parent=4"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cliniqueveterinairemistral.com\/index.php\/wp-json\/wp\/v2\/categories?post=4"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cliniqueveterinairemistral.com\/index.php\/wp-json\/wp\/v2\/tags?post=4"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}